{"id":36687,"date":"2025-06-04T11:59:23","date_gmt":"2025-06-04T09:59:23","guid":{"rendered":"https:\/\/shop.lattebusche.com\/?page_id=36687"},"modified":"2025-07-25T11:39:29","modified_gmt":"2025-07-25T09:39:29","slug":"invita-un-amico","status":"publish","type":"page","link":"https:\/\/shop.lattebusche.com\/it\/invita-un-amico\/","title":{"rendered":"Invita un amico"},"content":{"rendered":"<div  class=\"grids-section grids-is-advanced alignfull\" style=\"--_gs-gap-desktop:0px 0px;--_gs-m-desktop:0 0 0 0;--_gs-p-desktop:0 0 0 0;--_gs-bg-desktop:transparent none;--_gs-bg-xp-desktop:0px;--_gs-zi-desktop:auto;--_gs-d-desktop:block;--_gs-mw-desktop:calc(100% - 0 - 0);--_gs-gap-tablet:0px 0px;--_gs-m-tablet:0 0 0 0;--_gs-p-tablet:0 0 0 0;--_gs-bg-tablet:transparent none;--_gs-bg-xp-tablet:0px;--_gs-zi-tablet:auto;--_gs-d-tablet:block;--_gs-mw-tablet:calc(100% - 0 - 0);--_gs-gap-mobile:0px 0px;--_gs-m-mobile:0 0 0 0;--_gs-p-mobile:0 0 0 0;--_gs-bg-mobile:transparent none;--_gs-bg-xp-mobile:0px;--_gs-zi-mobile:auto;--_gs-d-mobile:block;--_gs-mw-mobile:calc(100% - 0 - 0);--_gs-columns:12;--_gs-rows:6\"><div class=\"grids-s-w_i\">\n<div class=\"grids-area\" style=\"--_ga-column:1\/13;--_ga-row:1\/7;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n<div class=\"atf-invita-amico\">\n    <div class=\"container-img-invita-amico\">\n        <img decoding=\"async\" src=\"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/invia-un-amico.webp\" alt=\"invita un amico\" class=\"img-invita-amico\">\n    <\/div>\n\n    <div class=\"container-titoli-invita-amico\">\n        <h1 class=\"h1-invita-amico\">Invita un amico<\/h1>\n        <div class=\"container-sconto-invita-amico\">\n            <span class=\"span-sconto\">PER TE<strong class=\"p-sconto\">SCONTO<\/strong><\/span> <span class=\"valore-sconto\">25%<\/span>\n            <br>\n        <\/div>\n        <span class=\"label-invita-amico\">PER IL TUO AMICO SCONTO DEL 10%<\/span>\n        <img decoding=\"async\" class=\"milk\" src=\"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/milk-scaled.webp\">\n    <\/div>\n<\/div>\n\n\n\n<\/div>\n<\/div><\/div><div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer spazio-vuoto\"><\/div><div  id=\"invita-amico-link\" class=\"grids-section margin grids-is-advanced\" style=\"--_gs-gap-desktop:0px 70px;--_gs-m-desktop:0 0 0 0;--_gs-p-desktop:0 0 0 0;--_gs-bg-desktop:transparent none;--_gs-bg-xp-desktop:0px;--_gs-zi-desktop:auto;--_gs-d-desktop:block;--_gs-mw-desktop:calc(100% - 0 - 0);--_gs-gap-tablet:0px 70px;--_gs-m-tablet:0 0 0 0;--_gs-p-tablet:0 0 0 0;--_gs-bg-tablet:transparent none;--_gs-bg-xp-tablet:0px;--_gs-zi-tablet:auto;--_gs-d-tablet:block;--_gs-mw-tablet:calc(100% - 0 - 0);--_gs-gap-mobile:0px 70px;--_gs-m-mobile:0 0 0 0;--_gs-p-mobile:0 0 0 0;--_gs-bg-mobile:transparent none;--_gs-bg-xp-mobile:0px;--_gs-zi-mobile:auto;--_gs-d-mobile:block;--_gs-mw-mobile:calc(100% - 0 - 0);--_gs-columns:12;--_gs-rows:6\"><div class=\"grids-s-w_i\">\n<div class=\"grids-area cta-refer-a-friend\" style=\"--_ga-column:2\/7;--_ga-row:2\/6;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n<div class=\"gens-refer-a-friend gens-raf-modern-template gens-refer-a-friend--generate guest_cookie_false\" data-link=\"https:\/\/shop.lattebusche.com\/it\/\">\n            \n<div class=\"gens-raf-text\">\n\t<h2>Il gusto di Lattebusche \u00e8 ancora pi\u00f9 buono quando si condivide!<\/h2>\nQuando <b>inviti un amico a scoprire Lattebusche<\/b>, entrambi riceverete un <b>codice sconto esclusivo<\/b> per il prossimo acquisto (valido su prodotti non in promozione).\u2028Ogni nuova iscrizione grazie a te \u00e8 un'occasione per <b>risparmiare<\/b> e goderti ancora di pi\u00f9 i <b>prodotti che ami.<\/b>\nPi\u00f9 amici inviti, pi\u00f9 vantaggi ottieni: \u00e8 semplice, veloce e conveniente.\u2028\nEffettua il login o registrati per ricevere il tuo link d\u2019invito: <b>Lattebusche premia chi condivide la bont\u00e0! <\/b><\/div>                    \t<div class=\"gens-raf-message\"><a href=\"https:\/\/shop.lattebusche.com\/it\/mio-account\/\" style=\"font-weight:600\"> \ud83d\udc49 Effettua il login o registrati qui per accedere al tuo link di invito.<\/a><\/div>\n                    <\/div>\n<div class=\"gens-refer-a-friend--guest guest_cookie_false\">\n    <div class=\"gens-refer-a-friend gens-raf-modern-template\" data-link=\"https:\/\/shop.lattebusche.com\/it\/\">\n            \n<div class=\"gens-raf-text\">\n\t<h2>Il gusto di Lattebusche \u00e8 ancora pi\u00f9 buono quando si condivide!<\/h2>\nQuando <b>inviti un amico a scoprire Lattebusche<\/b>, entrambi riceverete un <b>codice sconto esclusivo<\/b> per il prossimo acquisto (valido su prodotti non in promozione).\u2028Ogni nuova iscrizione grazie a te \u00e8 un'occasione per <b>risparmiare<\/b> e goderti ancora di pi\u00f9 i <b>prodotti che ami.<\/b>\nPi\u00f9 amici inviti, pi\u00f9 vantaggi ottieni: \u00e8 semplice, veloce e conveniente.\u2028\nEffettua il login o registrati per ricevere il tuo link d\u2019invito: <b>Lattebusche premia chi condivide la bont\u00e0! <\/b><\/div>                    \n<div class=\"gens-raf-reward\">\n\t<div>Tu ricevi<span>25%<\/span><\/div>\n\t<span><\/span>\n\t<div>Il tuo amico riceve<span>10%<\/span><\/div>\n<\/div>            <div class=\"gens-raf-field gens-raf-field--input\">\n\t<label for=\"raf_link\">Link di Invito<\/label>\n\t<div class=\"gens-copy\">\n\t\t<input type=\"text\" class=\"gens-raf-field--link\" disabled value=\"https:\/\/shop.lattebusche.com\/it\/\" \/>\n\t\t<span class=\"gens-ctc-modern\">\n\t\t\t<svg class=\"gens-copy-icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><rect width=\"14\" height=\"14\" x=\"8\" y=\"8\" rx=\"2\" ry=\"2\"\/><path d=\"M4 16c-1.1 0-2-.9-2-2V4c0-1.1.9-2 2-2h10c1.1 0 2 .9 2 2\"\/><\/svg>\n\t\t\t<svg class=\"gens-copied-icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"#73c050\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><path d=\"M18 6 7 17l-5-5\"\/><path d=\"m22 10-7.5 7.5L13 16\"\/><\/svg>\t\t\t\n\t\t<\/span>\n\t<\/div>\n<\/div>\n            <div class=\"gens-raf-field gens-raf-field--social\">\n\t<label for=\"raf_link\">Condivisione Social<\/label>\n\t<div class=\"gens-referral_share\">\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/shop.lattebusche.com\/it\/\" class=\"gens-referral_share__wa\" data-title=\"\">\n\t\t\t<svg height=\"100%\" version=\"1.1\" viewBox=\"0 0 512 512\" width=\"100%\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M373.295,307.064c-6.37,-3.188 -37.687,-18.596 -43.526,-20.724c-5.838,-2.126 -10.084,-3.187 -14.331,3.188c-4.246,6.376 -16.454,20.725 -20.17,24.976c-3.715,4.251 -7.431,4.785 -13.8,1.594c-6.37,-3.187 -26.895,-9.913 -51.225,-31.616c-18.935,-16.89 -31.72,-37.749 -35.435,-44.126c-3.716,-6.377 -0.397,-9.824 2.792,-13c2.867,-2.854 6.371,-7.44 9.555,-11.16c3.186,-3.718 4.247,-6.377 6.37,-10.626c2.123,-4.252 1.062,-7.971 -0.532,-11.159c-1.591,-3.188 -14.33,-34.542 -19.638,-47.298c-5.171,-12.419 -10.422,-10.737 -14.332,-10.934c-3.711,-0.184 -7.963,-0.223 -12.208,-0.223c-4.246,0 -11.148,1.594 -16.987,7.969c-5.838,6.377 -22.293,21.789 -22.293,53.14c0,31.355 22.824,61.642 26.009,65.894c3.185,4.252 44.916,68.59 108.816,96.181c15.196,6.564 27.062,10.483 36.312,13.418c15.259,4.849 29.145,4.165 40.121,2.524c12.238,-1.827 37.686,-15.408 42.995,-30.286c5.307,-14.882 5.307,-27.635 3.715,-30.292c-1.592,-2.657 -5.838,-4.251 -12.208,-7.44m-116.224,158.693l-0.086,0c-38.022,-0.015 -75.313,-10.23 -107.845,-29.535l-7.738,-4.592l-80.194,21.037l21.405,-78.19l-5.037,-8.017c-21.211,-33.735 -32.414,-72.726 -32.397,-112.763c0.047,-116.825 95.1,-211.87 211.976,-211.87c56.595,0.019 109.795,22.088 149.801,62.139c40.005,40.05 62.023,93.286 62.001,149.902c-0.048,116.834 -95.1,211.889 -211.886,211.889m180.332,-392.224c-48.131,-48.186 -112.138,-74.735 -180.335,-74.763c-140.514,0 -254.875,114.354 -254.932,254.911c-0.018,44.932 11.72,88.786 34.03,127.448l-36.166,132.102l135.141,-35.45c37.236,20.31 79.159,31.015 121.826,31.029l0.105,0c140.499,0 254.87,-114.366 254.928,-254.925c0.026,-68.117 -26.467,-132.166 -74.597,-180.352\" \/><\/svg>\n\t\t<\/a>\n\t<\/div>\n<\/div>            <\/div><\/div>\n<\/div>\n\n<div class=\"grids-area\" style=\"--_ga-column:7\/12;--_ga-row:2\/6;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n<figure class=\"wp-block-image size-full img-amico\"><img loading=\"lazy\" decoding=\"async\" width=\"588\" height=\"426\" src=\"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/illustrazione-lattebusche-e1749048741870.png\" alt=\"\" class=\"wp-image-36770\" srcset=\"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/illustrazione-lattebusche-e1749048741870.png 588w, https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/illustrazione-lattebusche-e1749048741870-300x217.png 300w\" sizes=\"auto, (max-width: 588px) 100vw, 588px\" \/><\/figure>\n<\/div>\n<\/div><\/div><div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer spazio-vuoto\"><\/div><div  class=\"grids-section sfondo-azzurro grids-is-advanced alignfull\" style=\"--_gs-gap-desktop:0px 0px;--_gs-m-desktop:0 0 0 0;--_gs-p-desktop:0 0 0 0;--_gs-bg-desktop:transparent none;--_gs-bg-xp-desktop:0px;--_gs-zi-desktop:auto;--_gs-d-desktop:block;--_gs-mw-desktop:calc(100% - 0 - 0);--_gs-gap-tablet:0px 0px;--_gs-m-tablet:0 0 0 0;--_gs-p-tablet:0 0 0 0;--_gs-bg-tablet:transparent none;--_gs-bg-xp-tablet:0px;--_gs-zi-tablet:auto;--_gs-d-tablet:block;--_gs-mw-tablet:calc(100% - 0 - 0);--_gs-gap-mobile:0px 0px;--_gs-m-mobile:0 0 0 0;--_gs-p-mobile:0 0 0 0;--_gs-bg-mobile:transparent none;--_gs-bg-xp-mobile:0px;--_gs-zi-mobile:auto;--_gs-d-mobile:block;--_gs-mw-mobile:calc(100% - 0 - 0);--_gs-columns:12;--_gs-rows:6\"><div class=\"grids-s-w_i\">\n<div class=\"grids-area\" style=\"--_ga-column:1\/13;--_ga-row:1\/7;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer spazio-vuoto\"><\/div>\n\n<h2 class=\"wp-block-heading has-text-align-center\">Ottieni il tuo sconto in 4 semplici step<\/h2>\n\n<div class=\"referral-steps\">\n  <div class=\"step\">\n    <div class=\"circle\">1<\/div>\n    <p>Accedi al tuo account o registrati<\/p>\n  <\/div>\n  <div class=\"dashed-line\"><img decoding=\"async\" src=\"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/Vector-1.svg\"><\/div>\n  <div class=\"step\">\n    <div class=\"circle\">2<\/div>\n    <p>Condividi il tuo invito con amici e familiari via messaggio, email o link<\/p>\n  <\/div>\n  <div class=\"dashed-line\"><img decoding=\"async\" src=\"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/Vector-2.svg\"><\/div>\n  <div class=\"step\">\n    <div class=\"circle\">3<\/div>\n    <p>Una volta che il tuo amico ha effettuato il suo primo ordine, riceverai uno <strong>sconto del 25%<\/strong> sul tuo prossimo acquisto<\/p>\n  <\/div>\n  <div class=\"dashed-line\"><img decoding=\"async\" src=\"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/Vector-1.svg\"><\/div>\n  <div class=\"step\">\n    <div class=\"circle\">4<\/div>\n    <p>Anche il tuo amico ricever\u00e0 uno <strong>sconto del 10%<\/strong> sul suo primo ordine<\/p>\n  <\/div>\n<\/div>\n\n\n<\/div>\n<\/div><\/div><div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer spazio-vuoto\"><\/div><div  class=\"grids-section margin grids-is-advanced\" style=\"--_gs-gap-desktop:0px 0px;--_gs-m-desktop:0 0 0 0;--_gs-p-desktop:0 0 0 0;--_gs-bg-desktop:transparent none;--_gs-bg-xp-desktop:0px;--_gs-zi-desktop:auto;--_gs-d-desktop:block;--_gs-mw-desktop:calc(100% - 0 - 0);--_gs-gap-tablet:0px 0px;--_gs-m-tablet:0 0 0 0;--_gs-p-tablet:0 0 0 0;--_gs-bg-tablet:transparent none;--_gs-bg-xp-tablet:0px;--_gs-zi-tablet:auto;--_gs-d-tablet:block;--_gs-mw-tablet:calc(100% - 0 - 0);--_gs-gap-mobile:0px 0px;--_gs-m-mobile:0 0 0 0;--_gs-p-mobile:0 0 0 0;--_gs-bg-mobile:transparent none;--_gs-bg-xp-mobile:0px;--_gs-zi-mobile:auto;--_gs-d-mobile:block;--_gs-mw-mobile:calc(100% - 0 - 0);--_gs-columns:12;--_gs-rows:6\"><div class=\"grids-s-w_i\">\n<div class=\"grids-area\" style=\"--_ga-column:3\/11;--_ga-row:2\/6;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n<h2 class=\"wp-block-heading\">FAQ<\/h2>\n\n<div class=\"wp-block-advgb-accordions advgb-accordions-c999e7ef-7a42-40b0-9850-c0b300c2a9fe advgb-accordion-wrapper\"><div class=\"wp-block-advgb-accordion-item advgb-accordion-item fisarmonica-azzurra\" style=\"margin-bottom:15px\"><div class=\"advgb-accordion-header\" style=\"background-color:#000000;color:#eee;border-style:solid;border-width:1px;border-radius:2px\"><span class=\"advgb-accordion-header-icon\"><svg fill=\"#fff\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\"><path fill=\"none\" d=\"M0,0h24v24H0V0z\"><\/path><path d=\"M12,5.83L15.17,9l1.41-1.41L12,3L7.41,7.59L8.83,9L12,5.83z M12,18.17L8.83,15l-1.41,1.41L12,21l4.59-4.59L15.17,15 L12,18.17z\"><\/path><\/svg><\/span><h4 class=\"advgb-accordion-header-title\" style=\"color:inherit\">Come funziona<\/h4><\/div><div class=\"advgb-accordion-body\" style=\"border-style:solid !important;border-width:1px !important;border-color:undefined !important;border-top:none !important;border-radius:2px !important\"><p>Quando l\u2019amico invitato clicca sul link d\u2019invito ed effettua il suo primo ordine, <strong>riceve subito uno sconto del 10% applicato direttamente al carrello<\/strong> (esclusi i prodotti gi\u00e0 in offerta). Dopo il completamento dell\u2019ordine, anche chi ha inviato l\u2019invito ricever\u00e0 uno sconto del 25% sul prossimo acquisto (esclusi i prodotti gi\u00e0 in offerta).<\/p><\/div><\/div>\n\n<div class=\"wp-block-advgb-accordion-item advgb-accordion-item\" style=\"margin-bottom:15px\"><div class=\"advgb-accordion-header\" style=\"background-color:#000000;color:#eee;border-style:solid;border-width:1px;border-radius:2px\"><span class=\"advgb-accordion-header-icon\"><svg fill=\"#fff\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\"><path fill=\"none\" d=\"M0,0h24v24H0V0z\"><\/path><path d=\"M12,5.83L15.17,9l1.41-1.41L12,3L7.41,7.59L8.83,9L12,5.83z M12,18.17L8.83,15l-1.41,1.41L12,21l4.59-4.59L15.17,15 L12,18.17z\"><\/path><\/svg><\/span><h4 class=\"advgb-accordion-header-title\" style=\"color:inherit\">A chi \u00e8 rivolto<\/h4><\/div><div class=\"advgb-accordion-body\" style=\"border-style:solid !important;border-width:1px !important;border-color:undefined !important;border-top:none !important;border-radius:2px !important\"><p>Il programma \u00e8 rivolto a tutti gli utenti gi\u00e0 iscritti al sito Lattebusche e ai loro amici (non appartenenti allo stesso nucleo abitativo). Invita chi vuoi far scoprire la qualit\u00e0 dei nostri prodotti!<\/p><\/div><\/div>\n\n<div class=\"wp-block-advgb-accordion-item advgb-accordion-item\" style=\"margin-bottom:15px\"><div class=\"advgb-accordion-header\" style=\"background-color:#000000;color:#eee;border-style:solid;border-width:1px;border-radius:2px\"><span class=\"advgb-accordion-header-icon\"><svg fill=\"#fff\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\"><path fill=\"none\" d=\"M0,0h24v24H0V0z\"><\/path><path d=\"M12,5.83L15.17,9l1.41-1.41L12,3L7.41,7.59L8.83,9L12,5.83z M12,18.17L8.83,15l-1.41,1.41L12,21l4.59-4.59L15.17,15 L12,18.17z\"><\/path><\/svg><\/span><h4 class=\"advgb-accordion-header-title\" style=\"color:inherit\">Quando e come ricevo lo sconto<\/h4><\/div><div class=\"advgb-accordion-body\" style=\"border-style:solid !important;border-width:1px !important;border-color:undefined !important;border-top:none !important;border-radius:2px !important\"><p>Dopo che l\u2019amico invitato avr\u00e0 ricevuto la merce del suo primo acquisto, il codice sconto verr\u00e0 inviato via email e sar\u00e0 visibile anche nella sezione dedicata nella pagina del proprio account.<\/p><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div><div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer spazio-vuoto\"><\/div><div  class=\"grids-section grids-is-advanced\" style=\"--_gs-gap-desktop:0px 0px;--_gs-m-desktop:0 0 0 0;--_gs-p-desktop:0 0 0 0;--_gs-bg-desktop:transparent none;--_gs-bg-xp-desktop:0px;--_gs-zi-desktop:auto;--_gs-d-desktop:block;--_gs-mw-desktop:calc(100% - 0 - 0);--_gs-gap-tablet:0px 0px;--_gs-m-tablet:0 0 0 0;--_gs-p-tablet:0 0 0 0;--_gs-bg-tablet:transparent none;--_gs-bg-xp-tablet:0px;--_gs-zi-tablet:auto;--_gs-d-tablet:block;--_gs-mw-tablet:calc(100% - 0 - 0);--_gs-gap-mobile:0px 0px;--_gs-m-mobile:0 0 0 0;--_gs-p-mobile:0 0 0 0;--_gs-bg-mobile:transparent none;--_gs-bg-xp-mobile:0px;--_gs-zi-mobile:auto;--_gs-d-mobile:block;--_gs-mw-mobile:calc(100% - 0 - 0);--_gs-columns:12;--_gs-rows:6\"><div class=\"grids-s-w_i\">\n<div class=\"grids-area\" style=\"--_ga-column:1\/13;--_ga-row:1\/8;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n\n<div class=\"table-wrapper\">\n  <table class=\"table-benefits\">\n    <!-- RIGA 1 -->\n    <tr>\n      <td class=\"img-benefit\"><img decoding=\"async\" src=\"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/lattebusche-shop.png\" alt=\"Lattebusche logo\"><\/td>\n      <td>\n        <ul class=\"features\">\n          <li><i class=\"fas fa-check\"><\/i>Prodotti freschi<\/li>\n          <li><i class=\"fas fa-check\"><\/i>Spedizioni refrigerate entro 5 giorni lavorativi<\/li>\n        <\/ul>\n      <\/td>\n      <td class=\"discount\"><span>0%<\/span> <a href=\"https:\/\/shop.lattebusche.com\/it\/categoria-prodotto\/offerte\/\" target=\"_blank\" class=\"button-mobile cta-white\">Acquista i prodotti<\/a><\/td>\n      <td class=\"cta cta-white\"><a href=\"https:\/\/shop.lattebusche.com\/it\/categoria-prodotto\/offerte\/\" target=\"_blank\">Acquista i prodotti<\/a><\/td>\n    <\/tr>\n\n    <!-- RIGA 2 -->\n    <tr>\n      <td class=\"img-benefit\"><img decoding=\"async\" src=\"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/coupon.png\" alt=\"Gift icon\"><\/td>\n      <td>\n        <ul class=\"features\">\n          <li><i class=\"fas fa-check\"><\/i>Sconto riservato solo agli iscritti<\/li>\n          <li><i class=\"fas fa-check\"><\/i>Ricevi offerte esclusive in anteprima<\/li>\n        <\/ul>\n      <\/td>\n      <td class=\"discount\"><span>10%<\/span> <a href=\"#banner-newsletter-1\" class=\"button-mobile cta-white\">Iscriviti alla newsletter<\/a><\/td>\n      <td class=\"cta cta-white\"><a href=\"#banner-newsletter-1\">Iscriviti alla newsletter<\/a><\/td>\n    <\/tr>\n\n    <!-- RIGA 3 -->\n    <tr>\n      <td class=\"img-benefit\"><img decoding=\"async\" src=\"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/illustrazione-lattebusche-e1749048741870.png\" alt=\"Invita un amico\"><\/td>\n      <td>\n        <ul class=\"features\">\n          <li><i class=\"fas fa-check\"><\/i>Tu e il tuo amico risparmiate <strong>subito<\/strong><\/li>\n          <li><i class=\"fas fa-check\"><\/i>Pi\u00f9 amici inviti, pi\u00f9 sconti accumuli<\/li>\n          <li><i class=\"fas fa-check\"><\/i>\u00c8 facile e gratuito: condividi il link!<\/li>\n        <\/ul>\n      <\/td>\n      <td class=\"discount\"><span>25%<\/span> <a href=\"#invita-amico-link\" class=\"button-mobile cta-blue\">Invita un amico<\/a><\/td>\n      <td class=\"cta cta-blue\"><a href=\"#invita-amico-link\">Invita un amico<\/a><\/td>\n    <\/tr>\n  <\/table>\n<\/div>\n\n\n\n<div class=\"table-mobile\">\n  <div class=\"row-1\">\n    <img decoding=\"async\" src=\"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/lattebusche-shop.png\" alt=\"Lattebusche logo\">\n    <ul class=\"features\">\n      <li><i class=\"fas fa-check\"><\/i>Prodotti freschi<\/li>\n      <li><i class=\"fas fa-check\"><\/i>Spedizioni refrigerate entro 5 giorni lavorativi<\/li>\n    <\/ul>\n    <span>0%<\/span>\n    <a href=\"https:\/\/shop.lattebusche.com\/it\/categoria-prodotto\/offerte\/\" target=\"_blank\" class=\"button-mobile cta-white\">Acquista i prodotti<\/a>\n  <\/div>\n\n  <div class=\"row-1\">\n    <img decoding=\"async\" src=\"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/coupon.png\" alt=\"Gift icon\">\n    <ul class=\"features\">\n      <li><i class=\"fas fa-check\"><\/i>Sconto riservato solo agli iscritti<\/li>\n      <li><i class=\"fas fa-check\"><\/i>Ricevi offerte esclusive in anteprima<\/li>\n    <\/ul>\n    <span>10%<\/span>\n    <a href=\"#banner-newsletter-1\" class=\"button-mobile cta-white\">Iscriviti alla newsletter<\/a>\n  <\/div>\n\n  <div class=\"row-1\">\n    <img decoding=\"async\" src=\"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/illustrazione-lattebusche-e1749048741870.png\" alt=\"Invita un amico\">\n    <ul class=\"features\">\n      <li><i class=\"fas fa-check\"><\/i>Tu e il tuo amico risparmiate <strong>subito<\/strong><\/li>\n      <li><i class=\"fas fa-check\"><\/i>Pi\u00f9 amici inviti, pi\u00f9 sconti accumuli<\/li>\n      <li><i class=\"fas fa-check\"><\/i>\u00c8 facile e gratuito: condividi il link!<\/li>\n    <\/ul>\n    <span>25%<\/span>\n    <a href=\"#invita-amico-link\" class=\"button-mobile cta-blue\">Invita un amico<\/a>\n  <\/div>\n<\/div>\n<\/div>\n<\/div><\/div><div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer spazio-vuoto\"><\/div><style class=\"advgb-styles-renderer\">\ndiv#content.site-content.invita-un-amico {\n    padding: 0px;\n}\n\nh1.page-title.invita-un-amico {\n    display: none;\n}\n\ndiv#content.site-content.invita-un-amico .wrap {\n    max-width: 100vw !important;\n    margin: 0px;\n}\nimg.img-invita-amico {\n  height: -webkit-fill-available; \/* Safari\/Chrome *\/\n  height: -moz-available;         \/* Firefox *\/\n  height: 100%;                   \/* fallback *\/\n  object-fit: cover;\n  width: 100%;\n}\n.atf-invita-amico {\n    display: flex;\n    justify-content: flex-start;\n    max-height: 600px;\n}\n.container-img-invita-amico {\n    width: 60%;\n}\nmain.invita-un-amico .page-header {\n    display: none !important;\n}\n.container-titoli-invita-amico {\n    width: 40%;\n    display: flex;\n    flex-direction: column;\n    justify-content: center;\n    gap: 10px;\n    padding: 0px 0px;\n    background: linear-gradient(180deg, #034A7A 0%, #034A7A 37%, #0674BE);\n    margin-bottom: 30px;\n}\n.container-sconto-invita-amico {\n    display: flex;\n    gap: 20px;\n    z-index: 2;\n}\nh1.h1-invita-amico {\n    font-family: 'Sanchez';\n    font-size: clamp(36px, 6vw, 70px);\n    color: white;\n    font-weight: 400;\n    margin-left: 35px;\n}\n.container-titoli-invita-amico h1 {\n    z-index: 2;\n}\nspan.label-invita-amico {\n    z-index: 2;\n}\nspan.span-sconto {\n    display: flex;\n    flex-direction: column;\n    color: white;\n    font-size: clamp(16px, 2.5vw, 26px);\n    font-family: 'Roboto';\n    font-weight: 300;\n    line-height: normal;\n}\nstrong.p-sconto {\n    color: white;\n    font-family: 'Roboto';\n    font-size: clamp(28px, 4vw, 54px);\n    font-style: normal;\n    font-weight: 600;\n    line-height: normal;\n}\nspan.valore-sconto {\n    font-size: clamp(36px, 6vw, 80px);\n    color: white;\n    font-weight: 900;\n    line-height: normal;\n    padding: 0px;\n    margin: 0px;\n    font-family: 'Roboto';\n    display: flex;\n    align-items: flex-end;\n    margin-bottom: -5px;\n}\nspan.label-invita-amico {\n    font-size: clamp(14px, 2vw, 26px);\n    width: fit-content;\n    background: white;\n    color: #0674BE;\n    font-family: 'Roboto';\n    padding: 5px 15px;\n    font-weight: 400;\n    line-height: normal;\n    margin-left: 35px;\n}\ndiv#content.invita-un-amico .wrap .content-area {\n    padding: 0px !important;\n}\nimg.milk {\n    object-fit: cover;\n    object-position: bottom;\n    position: absolute;\n    bottom: 0px;\n    width: -webkit-fill-available;\n}\n\n\n@media(max-width: 768px) {\n    .atf-invita-amico {\n        display: flex;\n        justify-content: flex-start;\n        flex-direction: column;\n        max-height: fit-content;\n    }\n    .container-img-invita-amico {\n        width: 100%;\n    }\n    .container-titoli-invita-amico {\n        width: 100%;\n        padding: 30px 0px 0px 0px;\n        min-height: 340px;\n        display: flex;\n        justify-content: flex-start;\n        margin-bottom: 0px;\n    }\n    h1.h1-invita-amico {\n        font-family: 'Sanchez';\n        font-size: 43px;\n        color: white;\n        font-weight: 400;\n    }\n    span.span-sconto {\n        display: flex;\n        flex-direction: column;\n        color: white;\n        font-size: 24px;\n        font-family: 'Roboto';\n        font-weight: 300;\n        line-height: normal;\n    }\n    strong.p-sconto {\n        color: white;\n        font-family: 'Roboto';\n        font-size: 43px;\n        font-style: normal;\n        font-weight: 600;\n        line-height: normal;\n    }\n    span.span-sconto {\n        display: flex;\n        flex-direction: column;\n        color: white;\n        font-size: 24px;\n        font-family: 'Roboto';\n        font-weight: 300;\n        line-height: normal;\n        justify-content: center;\n    }\n    span.valore-sconto {\n        font-size: 70px;\n    }\n    span.label-invita-amico {\n        font-size: 18px;\n    }\n    img.img-invita-amico {\n        height: 400px !important;\n        object-fit: cover;\n        width: 100%;\n    }\n    img.milk {\n        height: 105px;\n        object-fit: cover;\n        object-position: bottom;\n    }\n}\n\n.referral-steps {\n  display: flex;\n  align-items: flex-start;\n  justify-content: center;\n  gap: 20px;\n  padding: 40px 20px;\n  flex-wrap: nowrap;\n}\n\n.step {\n  text-align: center;\n  max-width: 200px;\n}\n\n.circle {\n  background-color: #006eb8;\n  color: white;\n  width: 60px;\n  height: 60px;\n  border-radius: 50%;\n  font-size: 24px;\n  display: flex;\n  align-items: center;\n  justify-content: center;\n  margin: 0 auto 10px auto;\n}\n\n.referral-steps {\n  display: flex;\n  align-items: flex-start;\n  justify-content: center;\n  gap: 20px;\n  padding: 40px 20px;\n  flex-wrap: wrap;\n  margin-top: 30px;\n  margin-bottom: 30px;\n}\n\n.grids-section.sfondo-azzurro {\n    background: #AAD3EF4D;\n}\n\n.step p {\n    font-size: 16px;\n}\n\n.dashed-line {\n    margin-top: 20px;\n}\n\n@media(max-width: 768px){\n  .referral-steps {\n      display: flex;\n      align-items: center;\n      justify-content: center;\n      gap: 20px;\n      padding: 0px 20px;\n      flex-wrap: wrap;\n      margin-top: 0px;\n      margin-bottom: 30px;\n      flex-direction: column;\n  }\n  .dashed-line {\n      transform: rotate(88deg);\n      width: 100px;\n      height: auto;\n  }\n  .step {\n      text-align: center;\n      max-width: 200px;\n      margin: 45px 0px 20px 0px;\n  }\n}\n\n.cta-white a {\n    background-color: #0071ce;\n    height: 100px;\n    display: flex;\n    align-items: center;\n    justify-content: center;\n}\n.table-wrapper {\n    width: 65%;\n    margin: 0 auto;\n    font-family: sans-serif;\n    box-shadow: 0 5px 15px rgb(0 0 0 \/ 35%);\n}\n.table-benefits {\n  width: 100%;\n  border-collapse: collapse;\n}\n.table-benefits tr {\n  border-bottom: 2px solid #eee;\n}\n.table-benefits td {\n  padding: 20px;\n  vertical-align: middle;\n  text-align: left;\n}\n.table-benefits td img {\n    max-height: 112px;\n}\n.features {\n  font-size: 16px;\n  line-height: 1.8;\n  padding-left: 0;\n  margin: 0;\n}\n.features li {\n  list-style: none;\n  margin-bottom: 8px;\n}\n.features li i {\n  color: green;\n  margin-right: 8px;\n}\n.discount {\n  font-size: 32px;\n  font-weight: bold;\n  text-align: center;\n  white-space: nowrap;\n}\n.cta {\n  text-align: center;\n}\n.cta a {\n    display: inline-block;\n    font-weight: bold;\n    padding: 15px 25px;\n    text-decoration: none;\n    border-radius: 4px;\n    color: white;\n    height: 180px;\n    display: flex;\n    align-items: center;\n    justify-content: center;\n}\n.cta-white a {\n    background-color: #fff;\n    color: #006dc6;\n}\n.cta-blue a {\n  background-color: #006dc6;\n}\n.table-benefits tr:last-child .discount {\n  color: #2ca058;\n}\ntd a {\n    text-align: center;\n    font-family: 'Roboto';\n    font-size: 20px;\n    font-weight: 500;\n}\ntd.cta.cta-white {\n    padding: 0px;\n}\ntable.table-benefits {\n    margin: 0px;\n}\ntd.cta.cta-blue {\n    padding: 0px;\n}\ntd.cta.cta-blue a {\n    width: 100%;\n    border-radius: 0px;\n    display: flex;\n    align-content: center;\n    align-items: center;\n    justify-content: center;\n    color: white;\n}\nul.features {\n    margin: 0px;\n}\nul.features li {\n    font-size: 15px !important;\n}\ntd.img-benefit {\n    display: flex;\n    height: 180px;\n    justify-content: center;\n    align-items: center;\n    border-color: transparent;\n}\na.button-mobile {\n    display: none;\n}\ntd.cta.cta-blue a:hover {\n    color: white;\n}\n\n  .table-wrapper {\n    display: block;\n  }\n  .table-mobile{\n    display: none;\n  }\n\n\n@media(max-width: 768px) {\n  .table-wrapper {\n    display: none;\n  }\n  .table-mobile {\n      display: flex;\n      flex-direction: column;\n      align-items: center;\n  }\n  .row-1 img {\n      width: 185px;\n      margin-bottom: 20px;\n  }\n    .row-1 {\n        width: 80%;\n        display: flex;\n        flex-direction: column;\n        align-items: center;\n        border-style: solid;\n        border-width: 0px 0px 1px 0px;\n        padding-bottom: 40px;\n        margin: 20px auto;\n    }\n  ul.features {\n      display: flex;\n      flex-direction: column;\n      align-items: center;\n      margin-bottom: 20px;\n  }\n  a.button-mobile {\n      display: block;\n  }\n  a.button-mobile {\n      display: block;\n      border-style: solid;\n      border-width: 1px;\n      padding: 10px 20px;\n      margin-top: 15px;\n  }\n  a.button-mobile.cta-blue {\n      color: white;\n      background: #0674BE;\n  }\n}\n<\/style>","protected":false},"excerpt":{"rendered":"","protected":false},"author":4148,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"class_list":["post-36687","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Invita un amico - Lattebusche shop online<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shop.lattebusche.com\/it\/invita-un-amico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Invita un amico - Lattebusche shop online\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shop.lattebusche.com\/it\/invita-un-amico\/\" \/>\n<meta property=\"og:site_name\" content=\"Lattebusche shop online\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-25T09:39:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/invia-un-amico.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/shop.lattebusche.com\/it\/invita-un-amico\/\",\"url\":\"https:\/\/shop.lattebusche.com\/it\/invita-un-amico\/\",\"name\":\"Invita un amico - Lattebusche shop online\",\"isPartOf\":{\"@id\":\"https:\/\/shop.lattebusche.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/shop.lattebusche.com\/it\/invita-un-amico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/shop.lattebusche.com\/it\/invita-un-amico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/invia-un-amico.webp\",\"datePublished\":\"2025-06-04T09:59:23+00:00\",\"dateModified\":\"2025-07-25T09:39:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/shop.lattebusche.com\/it\/invita-un-amico\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/shop.lattebusche.com\/it\/invita-un-amico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/shop.lattebusche.com\/it\/invita-un-amico\/#primaryimage\",\"url\":\"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/invia-un-amico.webp\",\"contentUrl\":\"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/invia-un-amico.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/shop.lattebusche.com\/it\/invita-un-amico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/shop.lattebusche.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Invita un amico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/shop.lattebusche.com\/it\/#website\",\"url\":\"https:\/\/shop.lattebusche.com\/it\/\",\"name\":\"Lattebusche shop online\",\"description\":\"Latteria della Vallata Feltrina\",\"publisher\":{\"@id\":\"https:\/\/shop.lattebusche.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/shop.lattebusche.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/shop.lattebusche.com\/it\/#organization\",\"name\":\"Lattebusche\",\"url\":\"https:\/\/shop.lattebusche.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/shop.lattebusche.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2022\/06\/cropped-Logo_shop-online.jpg\",\"contentUrl\":\"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2022\/06\/cropped-Logo_shop-online.jpg\",\"width\":834,\"height\":306,\"caption\":\"Lattebusche\"},\"image\":{\"@id\":\"https:\/\/shop.lattebusche.com\/it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Invita un amico - Lattebusche shop online","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shop.lattebusche.com\/it\/invita-un-amico\/","og_locale":"it_IT","og_type":"article","og_title":"Invita un amico - Lattebusche shop online","og_url":"https:\/\/shop.lattebusche.com\/it\/invita-un-amico\/","og_site_name":"Lattebusche shop online","article_modified_time":"2025-07-25T09:39:29+00:00","og_image":[{"url":"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/invia-un-amico.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/shop.lattebusche.com\/it\/invita-un-amico\/","url":"https:\/\/shop.lattebusche.com\/it\/invita-un-amico\/","name":"Invita un amico - Lattebusche shop online","isPartOf":{"@id":"https:\/\/shop.lattebusche.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shop.lattebusche.com\/it\/invita-un-amico\/#primaryimage"},"image":{"@id":"https:\/\/shop.lattebusche.com\/it\/invita-un-amico\/#primaryimage"},"thumbnailUrl":"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/invia-un-amico.webp","datePublished":"2025-06-04T09:59:23+00:00","dateModified":"2025-07-25T09:39:29+00:00","breadcrumb":{"@id":"https:\/\/shop.lattebusche.com\/it\/invita-un-amico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shop.lattebusche.com\/it\/invita-un-amico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/shop.lattebusche.com\/it\/invita-un-amico\/#primaryimage","url":"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/invia-un-amico.webp","contentUrl":"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2025\/06\/invia-un-amico.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/shop.lattebusche.com\/it\/invita-un-amico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/shop.lattebusche.com\/it\/"},{"@type":"ListItem","position":2,"name":"Invita un amico"}]},{"@type":"WebSite","@id":"https:\/\/shop.lattebusche.com\/it\/#website","url":"https:\/\/shop.lattebusche.com\/it\/","name":"Lattebusche shop online","description":"Latteria della Vallata Feltrina","publisher":{"@id":"https:\/\/shop.lattebusche.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shop.lattebusche.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/shop.lattebusche.com\/it\/#organization","name":"Lattebusche","url":"https:\/\/shop.lattebusche.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/shop.lattebusche.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2022\/06\/cropped-Logo_shop-online.jpg","contentUrl":"https:\/\/shop.lattebusche.com\/wp-content\/uploads\/2022\/06\/cropped-Logo_shop-online.jpg","width":834,"height":306,"caption":"Lattebusche"},"image":{"@id":"https:\/\/shop.lattebusche.com\/it\/#\/schema\/logo\/image\/"}}]}},"coauthors":[],"author_meta":{"author_link":"https:\/\/shop.lattebusche.com\/it\/author\/marco-perinel\/","display_name":"marco.perinel"},"relative_dates":{"created":"Pubblicato 1 anno fa","modified":"Aggiornato 12 mesi fa"},"absolute_dates":{"created":"Pubblicato il 4 Giugno 2025","modified":"Aggiornato il 25 Luglio 2025"},"absolute_dates_time":{"created":"Pubblicato il 4 Giugno 2025 11:59","modified":"Aggiornato il 25 Luglio 2025 11:39"},"featured_img_caption":"","featured_img":false,"series_order":"","_links":{"self":[{"href":"https:\/\/shop.lattebusche.com\/it\/wp-json\/wp\/v2\/pages\/36687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.lattebusche.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/shop.lattebusche.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/shop.lattebusche.com\/it\/wp-json\/wp\/v2\/users\/4148"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.lattebusche.com\/it\/wp-json\/wp\/v2\/comments?post=36687"}],"version-history":[{"count":126,"href":"https:\/\/shop.lattebusche.com\/it\/wp-json\/wp\/v2\/pages\/36687\/revisions"}],"predecessor-version":[{"id":37401,"href":"https:\/\/shop.lattebusche.com\/it\/wp-json\/wp\/v2\/pages\/36687\/revisions\/37401"}],"wp:attachment":[{"href":"https:\/\/shop.lattebusche.com\/it\/wp-json\/wp\/v2\/media?parent=36687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}